{"id":3161,"date":"2024-01-21T09:15:09","date_gmt":"2024-01-21T08:15:09","guid":{"rendered":"https:\/\/candlenco.fr\/?page_id=3161"},"modified":"2024-01-21T09:15:09","modified_gmt":"2024-01-21T08:15:09","slug":"conditions-generales-de-ventes","status":"publish","type":"page","link":"https:\/\/candlenco.fr\/index.php\/conditions-generales-de-ventes\/","title":{"rendered":"Conditions g\u00e9n\u00e9rales de ventes"},"content":{"rendered":"<div class=\"adn ads\" data-message-id=\"#msg-f:1788624890288145638\" data-legacy-message-id=\"18d278dc760c04e6\">\n<div class=\"gs\">\n<div class=\"\">\n<div id=\":187\" class=\"ii gt\">\n<div id=\":186\" class=\"a3s aiL \">\n<div dir=\"ltr\">\n<div>\n<div>\n<div id=\"m_6506205278305769553m_-3280158545071589274gmail-comp-lfqkzvrs\"><\/div>\n<\/div>\n<\/div>\n<div id=\"m_6506205278305769553m_-3280158545071589274gmail-bgLayers_comp-lazfwpbs\">\n<div id=\"m_6506205278305769553m_-3280158545071589274gmail-bgMedia_comp-lazfwpbs\">Les pr\u00e9sentes conditions g\u00e9n\u00e9rales de vente s&rsquo;appliquent \u00e0 toutes les ventes conclues sur le site internet Candlenco.fr<\/div>\n<\/div>\n<div>\n<div>\n<div>\n<div id=\"m_6506205278305769553m_-3280158545071589274gmail-comp-lazfwpbv4\">\n<div>\n<div>\n<div id=\"m_6506205278305769553m_-3280158545071589274gmail-comp-lazfwpbz1\">\n<p>Candlenco a le statut de Micro Entreprise.<\/p>\n<p>L&rsquo;entreprise Candle &amp; Co est situ\u00e9e au 93 avenue jean philippe rameau 30100 &#8211; France, dont l&rsquo;adresse URL du site est : <a href=\"https:\/\/candlenco.fr\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/candlenco.fr&amp;source=gmail&amp;ust=1705911174290000&amp;usg=AOvVaw1NpazrH2wYARtJjtFGojz6\">https:\/\/candlenco.fr<\/a><\/p>\n<p>Candle &amp; Co est joignable par mail \u00e0 l&rsquo;adresse\u00a0suivante : <a href=\"mailto:contact@candlenco.fr\" target=\"_blank\" rel=\"noopener\">contact@candlenco.fr<\/a><\/p>\n<p>N\u00b0 siret <span dir=\"auto\">98168681900013<\/span><\/p>\n<p>Le site Internet Candlenco commercialise les produits suivants :<\/p>\n<p>Bougies parfum\u00e9es, fondants parfum\u00e9s et accessoires parfum\u00e9s.<\/p>\n<p>Le client d\u00e9clare avoir pris connaissance et avoir accept\u00e9 les conditions g\u00e9n\u00e9rales de vente ant\u00e9rieurement \u00e0 la passation de sa commande. La validation de la commande vaut donc acceptation des conditions g\u00e9n\u00e9rales de vente.<\/p>\n<p>&nbsp;<\/p>\n<p>Article 1 &#8211; Principes<\/p>\n<p>Les pr\u00e9sentes conditions g\u00e9n\u00e9rales expriment l&rsquo;int\u00e9gralit\u00e9 des obligations des parties. En ce sens, l&rsquo;acheteur est r\u00e9put\u00e9 les accepter sans r\u00e9serve. Les pr\u00e9sentes conditions g\u00e9n\u00e9rales de vente s&rsquo;appliquent \u00e0 l&rsquo;exclusion de toutes autres conditions, et notamment celles applicables pour les ventes en magasin ou au moyen d&rsquo;autres circuits de distribution et de commercialisation.<\/p>\n<p>Elles sont accessibles sur le site internet Candlenco et pr\u00e9vaudront, le cas \u00e9ch\u00e9ant, sur toute autre version ou tout autre document contradictoire.<\/p>\n<p>Le vendeur se r\u00e9serve le droit de modifier ponctuellement ses conditions g\u00e9n\u00e9rales. Elles seront applicables d\u00e8s leur mise en ligne.<\/p>\n<p>Si une condition de vente venait \u00e0 faire d\u00e9faut, elle serait consid\u00e9r\u00e9e \u00eatre r\u00e9gie par les usages en vigueur dans le secteur de la vente \u00e0 distance dont les soci\u00e9t\u00e9s ont leur si\u00e8ge en France.<\/p>\n<p>&nbsp;<\/p>\n<p>Article 2 &#8211; Contenu<\/p>\n<p>Les pr\u00e9sentes conditions g\u00e9n\u00e9rales ont pour objet de d\u00e9finir les droits et les obligations des parties dans le cadre de la vente en ligne de biens propos\u00e9s par le vendeur \u00e0 l&rsquo;acheteur, \u00e0 partir du site internet Candlenco<\/p>\n<p>Les pr\u00e9sentes conditions ne concernent que les achats effectu\u00e9s sur le site Candlenco et livr\u00e9s exclusivement en France m\u00e9tropole.<\/p>\n<p>Ces achats concernent les produits suivants : bougies parfum\u00e9es en cire de soja, fondants parfum\u00e9s et accessoires parfum\u00e9s.<\/p>\n<p>&nbsp;<\/p>\n<p>Article 3 &#8211; Informations sur les produits et pr\u00e9cautions d&#8217;emploi<\/p>\n<p>Les produits r\u00e9gis par les pr\u00e9sentes conditions g\u00e9n\u00e9rales sont ceux qui figurent sur le site internet du vendeur et qui sont indiqu\u00e9s comme vendus et exp\u00e9di\u00e9s par le vendeur. Ils sont propos\u00e9s dans la limite des stocks disponibles.<\/p>\n<p>Les produits sont d\u00e9crits et pr\u00e9sent\u00e9s avec la plus grande exactitude possible. Toutefois, si des erreurs ou omissions ont pu se produire quant \u00e0 cette pr\u00e9sentation, la responsabilit\u00e9 du vendeur ne pourrait \u00eatre engag\u00e9e.<\/p>\n<p>Les photographies des produits ne sont pas contractuelles. S&rsquo;agissant de produits fabriqu\u00e9s \u00e0 la main, les couleurs et rendus peuvent varier d&rsquo;un produit \u00e0 l&rsquo;autre.<\/p>\n<p>L&rsquo;ensemble des produits, bougies, fondants et accessoires ne sont pas comestibles. Il est fortement recommand\u00e9 de tenir ces produits hors de port\u00e9e des enfants ET des animaux. En cas d&rsquo;ingestion ou de contact avec les muqueuses, le consommateur doit contacter un m\u00e9decin en urgence.<\/p>\n<p>&nbsp;<\/p>\n<p>Article 4 &#8211; Informations pr\u00e9contractuelles<\/p>\n<p>L&rsquo;acheteur reconna\u00eet avoir eu communication, pr\u00e9alablement \u00e0 la passation de sa commande et \u00e0 la conclusion du contrat, d&rsquo;une mani\u00e8re lisible et compr\u00e9hensible, des pr\u00e9sentes conditions g\u00e9n\u00e9rales de vente et de toutes les informations list\u00e9es \u00e0 l&rsquo;article L. 221-5 du code de la consommation.<\/p>\n<p>Sont transmises \u00e0 l&rsquo;acheteur, de mani\u00e8re claire et compr\u00e9hensible, les informations suivantes:<\/p>\n<p>&#8211; les caract\u00e9ristiques essentielles du bien;<\/p>\n<p>&#8211; le prix du bien et\/ou le mode de calcul du prix;<\/p>\n<p>&#8211; s&rsquo;il y a lieu, tous les frais suppl\u00e9mentaires de transport, de livraison ou d&rsquo;affranchissement et tous les autres frais \u00e9ventuels exigibles;<\/p>\n<p>&#8211; les informations relatives \u00e0 l&rsquo;identit\u00e9 du vendeur, \u00e0 ses coordonn\u00e9es postales, \u00e9lectroniques, et \u00e0 ses activit\u00e9s, celles relatives aux garanties l\u00e9gales, aux fonctionnalit\u00e9s du contenu num\u00e9rique et, le cas \u00e9ch\u00e9ant, \u00e0 son interop\u00e9rabilit\u00e9, \u00e0 l&rsquo;existence et aux modalit\u00e9s de mise en \u0153uvre des garanties et autres conditions contractuelles.<\/p>\n<p>&nbsp;<\/p>\n<p>Article 5 &#8211; La commande<\/p>\n<p>L&rsquo;acheteur a la possibilit\u00e9 de passer sa commande en ligne, \u00e0 partir du catalogue en ligne, pour tout produit, dans la limite des stocks disponibles.<\/p>\n<p>L&rsquo;acheteur sera inform\u00e9 dans les plus brefs d\u00e9lais de toute indisponibilit\u00e9 du produit ou du bien command\u00e9.<\/p>\n<p>Pour que la commande soit valid\u00e9e, l&rsquo;acheteur devra accepter, en cliquant \u00e0 l&rsquo;endroit indiqu\u00e9, les pr\u00e9sentes conditions g\u00e9n\u00e9rales. Il devra aussi choisir l&rsquo;adresse et le mode de livraison, et enfin valider le mode de paiement.<\/p>\n<p>La vente sera consid\u00e9r\u00e9e comme d\u00e9finitive:<\/p>\n<p>Apr\u00e8s l&rsquo;envoi \u00e0 l&rsquo;acheteur de la confirmation de l&rsquo;acceptation de la commande par le vendeur par courrier \u00e9lectronique et apr\u00e8s l&rsquo;encaissement par le vendeur de l\u2019int\u00e9gralit\u00e9 du prix.<\/p>\n<p>Toute commande vaut acceptation des prix et de la description des produits disponibles \u00e0 la vente. Toute contestation sur ce point interviendra dans le cadre d&rsquo;un \u00e9ventuel \u00e9change et des garanties ci-dessous mentionn\u00e9es.<\/p>\n<p>Dans certains cas, notamment d\u00e9faut de paiement, adresse erron\u00e9e ou autre probl\u00e8me sur le compte de l&rsquo;acheteur, le vendeur se r\u00e9serve le droit de bloquer la commande de l&rsquo;acheteur jusqu&rsquo;\u00e0 la r\u00e9solution du probl\u00e8me.<\/p>\n<p>Pour toute question relative au suivi d&rsquo;une commande, l&rsquo;acheteur peut appeler le num\u00e9ro de t\u00e9l\u00e9phone suivant: 0658468542 aux jours et horaires suivants: du lundi au samedi de 9h \u00e0 19h, ou envoyer un mail au vendeur \u00e0 l&rsquo;adresse <a href=\"mailto:contact@candlenco.fr\" target=\"_blank\" rel=\"noopener\">contact@candlenco.fr<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Article 6 &#8211; Signature \u00e9lectronique<\/p>\n<p>La fourniture en ligne du num\u00e9ro de carte bancaire de l&rsquo;acheteur et la validation finale de la commande vaudront preuve de l&rsquo;accord de l&rsquo;acheteur:<\/p>\n<p>&#8211; exigibilit\u00e9 des sommes dues au titre du bon de commande;<\/p>\n<p>&#8211; signature et acceptation expresse de toutes les op\u00e9rations effectu\u00e9es.<\/p>\n<p>En cas d&rsquo;utilisation frauduleuse de la carte bancaire, l&rsquo;acheteur est invit\u00e9, \u00e0 le contacter le vendeur au num\u00e9ro de t\u00e9l\u00e9phone suivant: 0658468542<\/p>\n<p>&nbsp;<\/p>\n<p>Article 6 &#8211; Confirmation de commande<\/p>\n<p>Le vendeur fournit \u00e0 l&rsquo;acheteur une confirmation de commande, par messagerie \u00e9lectronique.<\/p>\n<p>&nbsp;<\/p>\n<p>Article 7 &#8211; Preuve de la transaction<\/p>\n<p>Les registres informatis\u00e9s, conserv\u00e9s dans les syst\u00e8mes informatiques du vendeur dans des conditions raisonnables de s\u00e9curit\u00e9, seront consid\u00e9r\u00e9es comme les preuves des communications et des paiements intervenus entre les parties. l&rsquo;archivage des bons de commandes et des factures est effectu\u00e9 sur un support fiable et durable pouvant \u00eatre produit \u00e0 titre de preuve.<\/p>\n<p>&nbsp;<\/p>\n<p>Article 8 &#8211; Prix<\/p>\n<p>Le vendeur se r\u00e9serve le droit de modifier ses prix \u00e0 tout moment mais s&rsquo;engage \u00e0 appliquer les tarifs en vigueur indiqu\u00e9s au moment de la commande, sous r\u00e9serve de disponibilit\u00e9 \u00e0 cette date.<\/p>\n<p>Les prix sont indiqu\u00e9s en euros. Ils ne tiennent pas compte des frais de livraison, factur\u00e9s en suppl\u00e9ment, et indiqu\u00e9s avant la validation de la commande. Les prix tiennent compte de la TVA applicable au jour de la commande et tout changement du taux applicable TVA sera automatiquement r\u00e9percut\u00e9 sur le prix des produits de la boutique en ligne.<\/p>\n<p>Si une ou plusieurs taxes ou contributions, notamment environnementales, venaient \u00e0 \u00eatre cr\u00e9\u00e9es ou modifi\u00e9es, en hausse comme en baisse, ce changement pourrait \u00eatre r\u00e9percut\u00e9 sur le prix de vente des produits.<\/p>\n<p>&nbsp;<\/p>\n<p>Article 9 &#8211; Mode de paiement<\/p>\n<p>Il s&rsquo;agit d&rsquo;une commande avec obligation de paiement, ce qui signifie que la passation de la commande implique un r\u00e8glement de l&rsquo;acheteur. Pour r\u00e9gler sa commande, l&rsquo;acheteur dispose, \u00e0 son choix, de l&rsquo;ensemble des modes de paiement mis \u00e0 sa disposition par le vendeur et list\u00e9s sur le site du vendeur. L&rsquo;acheteur garantit au vendeur qu&rsquo;il dispose des autorisations \u00e9ventuellement n\u00e9cessaires pour utiliser le mode de paiement choisi par lui, lors de la validation du bon de commande. Le vendeur se r\u00e9serve le droit de suspendre toute gestion de commande et toute livraison en cas de refus d&rsquo;autorisation de paiement par carte bancaire de la part des organismes officiellement accr\u00e9dit\u00e9s ou en cas de non-paiement. Le vendeur se r\u00e9serve notamment le droit de refuser d&rsquo;effectuer une livraison ou d&rsquo;honorer une commande \u00e9manant d&rsquo;un acheteur qui n&rsquo;aurait pas r\u00e9gl\u00e9 totalement ou partiellement une commande pr\u00e9c\u00e9dente ou avec lequel un litige de paiement serait en cours d&rsquo;administration.<\/p>\n<p>Le paiement du prix s&rsquo;effectue en totalit\u00e9 au jour de la commande, selon les modalit\u00e9s suivantes:<\/p>\n<p>&#8211; Carte bancaire<\/p>\n<p>&#8211; Paypal<\/p>\n<p>&nbsp;<\/p>\n<p>Article 10 &#8211; Disponibilit\u00e9 des produits &#8211; Remboursement &#8211; R\u00e9solution<\/p>\n<p>Sauf en cas de force majeure ou lors des p\u00e9riodes de fermeture de la boutique en ligne qui seront clairement annonc\u00e9es sur la page d&rsquo;accueil du site, les d\u00e9lais d&rsquo;exp\u00e9dition seront, dans la limite des stocks disponibles, ceux indiqu\u00e9s ci-dessous. Les d\u00e9lais d&rsquo;exp\u00e9dition courent \u00e0 compter de la date d&rsquo;enregistrement de la commande indiqu\u00e9e sur le mail de confirmation de la commande.<\/p>\n<p>Pour la cr\u00e9ation et la livraisons= en France M\u00e9tropolitaine le d\u00e9lai est en moyenne de 15 jours ouvr\u00e9s \u00e0 compter du jour suivant celui o\u00f9 l&rsquo;acheteur a pass\u00e9 sa commande, selon les modalit\u00e9s suivantes: Mondial Relay. En cas de forte demande ou au cours des f\u00eates de No\u00ebl, ce d\u00e9lai peut \u00eatre allong\u00e9, les d\u00e9lais seront communiqu\u00e9s \u00e0 travers le site et les r\u00e9seaux sociaux. Au plus tard, le d\u00e9lai sera de 30 jours ouvrables apr\u00e8s la conclusion du contrat.<\/p>\n<p>En cas d&rsquo;indisponibilit\u00e9 du produit command\u00e9, l&rsquo;acheteur en sera inform\u00e9 au plus t\u00f4t et aura la possibilit\u00e9 d&rsquo;annuler sa commande. L&rsquo;acheteur aura alors le choix de demander soit le remboursement des sommes vers\u00e9es dans les 14 jours au plus tard de leur versement, soit l&rsquo;\u00e9change du produit.<\/p>\n<p>&nbsp;<\/p>\n<p>Article 11 &#8211; Modalit\u00e9 de livraison<\/p>\n<p>La livraison s&rsquo;entend du transfert au consommateur de la possession physique ou du contr\u00f4le du bien. Les produits command\u00e9s sont livr\u00e9s selon les modalit\u00e9s et le d\u00e9lai pr\u00e9cis\u00e9 ci-dessus.<\/p>\n<p>Les produits sont livr\u00e9s au point de retrait partenaire de Mondial Relay choisi par l&rsquo;acheteur sur le bon de commande, l&rsquo;acheteur devra veiller \u00e0 son exactitude. Tout colis non r\u00e9cup\u00e9r\u00e9 au point relais dans un d\u00e9lai de 14 jours ou renvoy\u00e9 au vendeur \u00e0 cause d&rsquo;une adresse de livraison erron\u00e9e ou incompl\u00e8te sera r\u00e9exp\u00e9di\u00e9 \u00e0 l&rsquo;exp\u00e9diteur aux frais de l&rsquo;acheteur.<\/p>\n<p>En cas d&rsquo;un retour du colis \u00e0 l&rsquo;exp\u00e9diteur pour non r\u00e9cup\u00e9ration de ce dernier au point relais dans un d\u00e9lai de 14 jours apr\u00e8s la mise \u00e0 disposition au point de relais, candle&amp;co ne sera pas en mesure de prendre en charge les frais li\u00e9s au traitement du retour du colis et l&rsquo;acheteur ne pourra pr\u00e9tendre \u00e0 un remboursement du montant des frais de port engag\u00e9s \u00e0 l&rsquo;aller.<\/p>\n<p>L&rsquo;acheteur peut, \u00e0 sa demande, obtenir l&rsquo;envoi d&rsquo;une facture \u00e0 l&rsquo;adresse de facturation et non \u00e0 l&rsquo;adresse de livraison, en validant l&rsquo;option pr\u00e9vue \u00e0 cet effet sur le bon de commande.<\/p>\n<p>Si l&rsquo;acheteur est absent le jour de la livraison, le livreur laissera un avis de passage dans la bo\u00eete aux lettres, qui permettra de retirer le colis dans le bureau de poste le plus proche du domicile aux d\u00e9lais indiqu\u00e9s.<\/p>\n<p>Si au moment de la livraison, l&#8217;emballage d&rsquo;origine est ab\u00eem\u00e9, d\u00e9chir\u00e9, ouvert, l&rsquo;acheteur doit alors v\u00e9rifier l&rsquo;\u00e9tat des articles et contacter candlenco<\/p>\n<p>&nbsp;<\/p>\n<p>Article 12 &#8211; Erreurs de livraison<\/p>\n<p>L&rsquo;acheteur devra formuler aupr\u00e8s du vendeur le jour-m\u00eame de la livraison ou au plus tard le premier jour ouvr\u00e9 suivant la livraison, toute r\u00e9clamation d&rsquo;erreur de livraison et\/ou de non conformit\u00e9 des produits en nature ou en qualit\u00e9 par rapport aux indications figurant sur le bon de commande. Toute r\u00e9clamation formul\u00e9e au-del\u00e0 de ce d\u00e9lai sera rejet\u00e9e.<\/p>\n<p>La r\u00e9clamation pourra \u00eatre faite, par e-mail \u00e0 l&rsquo;adresse suivante:<\/p>\n<p><a href=\"mailto:contact@candlenco.fr\" target=\"_blank\" rel=\"noopener\">contact@candlenco.fr<\/a><\/p>\n<p>Toute r\u00e9clamation non effectu\u00e9e dans les r\u00e8gles d\u00e9finies ci-dessus et dans les d\u00e9lais impartis ne pourra \u00eatre prise en compte et d\u00e9gagera le vendeur de toute responsabilit\u00e9 vis-\u00e0-vis de l&rsquo;acheteur.<\/p>\n<p>&nbsp;<\/p>\n<p>Article 13 &#8211; Droit de r\u00e9tractation<\/p>\n<p>S&rsquo;agissant d&rsquo;articles personnalis\u00e9s, les dispositions de l&rsquo;Article L. 121-20-2, 3\u00b0 du Code de la Consommation s&rsquo;appliquent et privent le client de son d\u00e9lai de r\u00e9tractation de 14 jours et de retour des marchandises personnalis\u00e9es.<\/p>\n<p>Pour les articles non personnalis\u00e9s conform\u00e9ment aux disposition du code de la consommation, l&rsquo;acheteur dispose d&rsquo;un d\u00e9lai de 14 jours \u00e0 compter de la date de livraison de sa commande, pour retourner tout article ne lui convenant pas et demander l&rsquo;\u00e9change ou le remboursement sans p\u00e9nalit\u00e9, \u00e0 l&rsquo;exception des frais de retour qui restent \u00e0 la charge de l&rsquo;acheteur.<\/p>\n<p>Les retours sont \u00e0 effectuer dans leur \u00e9tat d&rsquo;origine et complets (emballages, accessoires&#8230;) permettant d&rsquo;\u00eatre re-commercialis\u00e9s \u00e0 l&rsquo;\u00e9tat neuf.<\/p>\n<p>Les produits endommag\u00e9s, salis ou incomplets ne sont pas repris.<\/p>\n<p>Le droit de r\u00e9tractation peut \u00eatre exerc\u00e9 sur demande par mail \u00e0 l&rsquo;adresse <a href=\"mailto:contact@candlenco.fr\" target=\"_blank\" rel=\"noopener\">contact@candlenco.fr<\/a> . La demande doit \u00eatre d\u00e9nu\u00e9e d&rsquo;ambigu\u00eft\u00e9 et doit exprimer la volont\u00e9 de se r\u00e9tracter.<\/p>\n<p>Les frais de retour sont \u00e0 la charge de l&rsquo;acheteur.<\/p>\n<p>L&rsquo;\u00e9change (sous r\u00e9serve de disponibilit\u00e9) ou le remboursement sera effectu\u00e9 dans un d\u00e9lai de 14 jours \u00e0 compter de la r\u00e9ception, par le vendeur, des produits retourn\u00e9s par l&rsquo;acheteur dans les conditions pr\u00e9vues ci-dessus.<\/p>\n<p>&nbsp;<\/p>\n<p>Article 14 &#8211; Propri\u00e9t\u00e9 intellectuelle<\/p>\n<p>Le contenu du site internet reste la propri\u00e9t\u00e9 du vendeur, candlenco seul titulaire des droits de propri\u00e9t\u00e9 intellectuelle sur ce contenu.<\/p>\n<p>Les acheteurs s&rsquo;engagent \u00e0 ne faire aucun usage de ce contenu; toute reproduction totale ou partielle de ce contenu est strictement interdite et est susceptible de constituer un d\u00e9lit de contrefa\u00e7on.<\/p>\n<p>&nbsp;<\/p>\n<p>Article 15 &#8211; Informatiques et Libert\u00e9s<\/p>\n<p>Les donn\u00e9es nominatives fournies par l&rsquo;acheteur sont n\u00e9cessaires au traitement de sa commande et \u00e0 l&rsquo;\u00e9tablissement des factures.<\/p>\n<p>L&rsquo;acheteur dispose d&rsquo;un droit d&rsquo;acc\u00e8s permanent, de modification, de rectification et d&rsquo;opposition s&rsquo;agissant des informations le concernant. Ce droit peut \u00eatre exerc\u00e9 dans les conditions et selon les modalit\u00e9s d\u00e9finies sur le site candlenco.<\/p>\n<p>&nbsp;<\/p>\n<p>Article 16 &#8211; Langue du contrat<\/p>\n<p>Les pr\u00e9sentes conditions g\u00e9n\u00e9rales de vente sont r\u00e9dig\u00e9es en langue fran\u00e7aise.<\/p>\n<p>&nbsp;<\/p>\n<p>Article 17 &#8211; R\u00e8glement des litiges<\/p>\n<p>Conform\u00e9ment \u00e0 l&rsquo;article 14 du R\u00e8glement (UE) n\u00b0524\/2013, la Commission Europ\u00e9enne a mis en place une plateforme de R\u00e8glement en Ligne des Litiges, facilitant le r\u00e8glement ind\u00e9pendant par voie extrajudiciaire des litiges en ligne entre consommateurs et professionnels de l&rsquo;Union europ\u00e9enne. Cette plateforme est accessible au lieu suivant: <a href=\"https:\/\/webgate.ec.europa.eu\/odr\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/webgate.ec.europa.eu\/odr\/&amp;source=gmail&amp;ust=1705911174290000&amp;usg=AOvVaw3j3DfUEgemeHs1aj4kD_FB\">https:\/\/webgate.ec.europa.eu\/<wbr \/>odr\/<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Article 18 &#8211; Loi applicable<\/p>\n<p>Les pr\u00e9sentes conditions g\u00e9n\u00e9rales sont soumis \u00e0 l&rsquo;application du droit fran\u00e7ais. Le tribunal comp\u00e9tent est le tribunal judiciaire. Il en est ainsi pour les r\u00e8gles de fond comme pour les r\u00e8gles de forme. En cas de litige ou de r\u00e9clamation, l&rsquo;acheteur s&rsquo;adressera en priorit\u00e9 au vendeur pour obtenir une solution \u00e0 l&rsquo;amiable.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"yj6qo\"><\/div>\n<div class=\"adL\"><\/div>\n<\/div>\n<div class=\"adL\"><\/div>\n<\/div>\n<\/div>\n<div class=\"hi\"><\/div>\n<div class=\"WhmR8e\" data-hash=\"0\"><\/div>\n<\/div>\n<\/div>\n<div class=\"ajx\"><\/div>\n<\/div>\n<div class=\"gA gt acV\">\n<div class=\"gB xu\">\n<div class=\"ip iq\">\n<div id=\":188\">\n<table class=\"cf wS\" role=\"presentation\">\n<tbody>\n<tr>\n<td class=\"amq\"><img decoding=\"async\" id=\":17g_0\" class=\"lazyload ajn bofPge\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-orig-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJMPirHtgSdGxICExISHHN6RB3O7u8U8S5gYwn7eWMQPA=s40-p\" name=\":17g\" data-hovercard-id=\"anthony.ribes@gmail.com\" \/><\/td>\n<td class=\"amr\">\n<div class=\"nr wR\">\n<div class=\"amn\"><\/div>\n<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"nH\">\n<div class=\"aHU hx\">\n<div role=\"list\">\n<div class=\"h7 ie\" tabindex=\"-1\" role=\"listitem\" aria-expanded=\"true\">\n<div class=\"Bk\">\n<div class=\"G3 G2\">\n<div>\n<div id=\":184\">\n<div class=\"gA gt acV\">\n<div class=\"gB xu\">\n<div class=\"ip iq\">\n<div id=\":188\">\n<table class=\"cf wS\" role=\"presentation\">\n<tbody>\n<tr>\n<td class=\"amr\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<div class=\"nH\">\n<div class=\"l2\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Les pr\u00e9sentes conditions g\u00e9n\u00e9rales de vente s&rsquo;appliquent \u00e0 toutes les [&#8230;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3161","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Conditions g\u00e9n\u00e9rales de ventes - Candle &amp; Co<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/candlenco.fr\/index.php\/conditions-generales-de-ventes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conditions g\u00e9n\u00e9rales de ventes - Candle &amp; Co\" \/>\n<meta property=\"og:description\" content=\"Les pr\u00e9sentes conditions g\u00e9n\u00e9rales de vente s&rsquo;appliquent \u00e0 toutes les [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/candlenco.fr\/index.php\/conditions-generales-de-ventes\/\" \/>\n<meta property=\"og:site_name\" content=\"Candle &amp; Co\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ribesjulie\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJMPirHtgSdGxICExISHHN6RB3O7u8U8S5gYwn7eWMQPA=s40-p\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/candlenco.fr\/index.php\/conditions-generales-de-ventes\/\",\"url\":\"https:\/\/candlenco.fr\/index.php\/conditions-generales-de-ventes\/\",\"name\":\"Conditions g\u00e9n\u00e9rales de ventes - Candle &amp; Co\",\"isPartOf\":{\"@id\":\"https:\/\/candlenco.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/candlenco.fr\/index.php\/conditions-generales-de-ventes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/candlenco.fr\/index.php\/conditions-generales-de-ventes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJMPirHtgSdGxICExISHHN6RB3O7u8U8S5gYwn7eWMQPA=s40-p\",\"datePublished\":\"2024-01-21T08:15:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/candlenco.fr\/index.php\/conditions-generales-de-ventes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/candlenco.fr\/index.php\/conditions-generales-de-ventes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/candlenco.fr\/index.php\/conditions-generales-de-ventes\/#primaryimage\",\"url\":\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJMPirHtgSdGxICExISHHN6RB3O7u8U8S5gYwn7eWMQPA=s40-p\",\"contentUrl\":\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJMPirHtgSdGxICExISHHN6RB3O7u8U8S5gYwn7eWMQPA=s40-p\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/candlenco.fr\/index.php\/conditions-generales-de-ventes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/candlenco.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conditions g\u00e9n\u00e9rales de ventes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/candlenco.fr\/#website\",\"url\":\"https:\/\/candlenco.fr\/\",\"name\":\"Candle & Co\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/candlenco.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/candlenco.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/candlenco.fr\/#organization\",\"name\":\"Candle & Co\",\"url\":\"https:\/\/candlenco.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/candlenco.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i0.wp.com\/candlenco.fr\/wp-content\/uploads\/2023\/11\/Logo.png?fit=250%2C250&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/candlenco.fr\/wp-content\/uploads\/2023\/11\/Logo.png?fit=250%2C250&ssl=1\",\"width\":250,\"height\":250,\"caption\":\"Candle & Co\"},\"image\":{\"@id\":\"https:\/\/candlenco.fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ribesjulie\",\"https:\/\/www.instagram.com\/candlenco23\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conditions g\u00e9n\u00e9rales de ventes - Candle &amp; Co","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/candlenco.fr\/index.php\/conditions-generales-de-ventes\/","og_locale":"fr_FR","og_type":"article","og_title":"Conditions g\u00e9n\u00e9rales de ventes - Candle &amp; Co","og_description":"Les pr\u00e9sentes conditions g\u00e9n\u00e9rales de vente s&rsquo;appliquent \u00e0 toutes les [...]","og_url":"https:\/\/candlenco.fr\/index.php\/conditions-generales-de-ventes\/","og_site_name":"Candle &amp; Co","article_publisher":"https:\/\/www.facebook.com\/ribesjulie","og_image":[{"url":"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJMPirHtgSdGxICExISHHN6RB3O7u8U8S5gYwn7eWMQPA=s40-p","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/candlenco.fr\/index.php\/conditions-generales-de-ventes\/","url":"https:\/\/candlenco.fr\/index.php\/conditions-generales-de-ventes\/","name":"Conditions g\u00e9n\u00e9rales de ventes - Candle &amp; Co","isPartOf":{"@id":"https:\/\/candlenco.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/candlenco.fr\/index.php\/conditions-generales-de-ventes\/#primaryimage"},"image":{"@id":"https:\/\/candlenco.fr\/index.php\/conditions-generales-de-ventes\/#primaryimage"},"thumbnailUrl":"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJMPirHtgSdGxICExISHHN6RB3O7u8U8S5gYwn7eWMQPA=s40-p","datePublished":"2024-01-21T08:15:09+00:00","breadcrumb":{"@id":"https:\/\/candlenco.fr\/index.php\/conditions-generales-de-ventes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/candlenco.fr\/index.php\/conditions-generales-de-ventes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/candlenco.fr\/index.php\/conditions-generales-de-ventes\/#primaryimage","url":"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJMPirHtgSdGxICExISHHN6RB3O7u8U8S5gYwn7eWMQPA=s40-p","contentUrl":"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJMPirHtgSdGxICExISHHN6RB3O7u8U8S5gYwn7eWMQPA=s40-p"},{"@type":"BreadcrumbList","@id":"https:\/\/candlenco.fr\/index.php\/conditions-generales-de-ventes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/candlenco.fr\/"},{"@type":"ListItem","position":2,"name":"Conditions g\u00e9n\u00e9rales de ventes"}]},{"@type":"WebSite","@id":"https:\/\/candlenco.fr\/#website","url":"https:\/\/candlenco.fr\/","name":"Candle & Co","description":"","publisher":{"@id":"https:\/\/candlenco.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/candlenco.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/candlenco.fr\/#organization","name":"Candle & Co","url":"https:\/\/candlenco.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/candlenco.fr\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/candlenco.fr\/wp-content\/uploads\/2023\/11\/Logo.png?fit=250%2C250&ssl=1","contentUrl":"https:\/\/i0.wp.com\/candlenco.fr\/wp-content\/uploads\/2023\/11\/Logo.png?fit=250%2C250&ssl=1","width":250,"height":250,"caption":"Candle & Co"},"image":{"@id":"https:\/\/candlenco.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ribesjulie","https:\/\/www.instagram.com\/candlenco23"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/candlenco.fr\/index.php\/wp-json\/wp\/v2\/pages\/3161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/candlenco.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/candlenco.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/candlenco.fr\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/candlenco.fr\/index.php\/wp-json\/wp\/v2\/comments?post=3161"}],"version-history":[{"count":1,"href":"https:\/\/candlenco.fr\/index.php\/wp-json\/wp\/v2\/pages\/3161\/revisions"}],"predecessor-version":[{"id":3162,"href":"https:\/\/candlenco.fr\/index.php\/wp-json\/wp\/v2\/pages\/3161\/revisions\/3162"}],"wp:attachment":[{"href":"https:\/\/candlenco.fr\/index.php\/wp-json\/wp\/v2\/media?parent=3161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}